{"id":611,"date":"2026-05-20T10:41:53","date_gmt":"2026-05-20T10:41:53","guid":{"rendered":"https:\/\/dusia.es\/?p=611"},"modified":"2026-05-20T10:41:54","modified_gmt":"2026-05-20T10:41:54","slug":"la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local","status":"publish","type":"post","link":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/","title":{"rendered":"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" style=\"font-size:16px\">El 2\u00ba Encuentro de trabajo re\u00fane en Sevilla a entidades locales para avanzar en la gesti\u00f3n de los Planes de Actuaci\u00f3n Integrados y abrir una nueva etapa de consolidaci\u00f3n de la iniciativa<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:16px\">La secretaria general de la FAMP, Yolanda S\u00e1ez, destaca que \u201cAndaluc\u00eda afronta uno de los mayores retos de desarrollo y gesti\u00f3n urbana de las \u00faltimas d\u00e9cadas, con una inversi\u00f3n global superior a los 865 millones, de los que m\u00e1s de 735 proceden de financiaci\u00f3n europea\u201d<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sevilla, 20 de mayo de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">La Federaci\u00f3n Andaluza de Municipios y Provincias ha celebrado en Sevilla el 2\u00ba Encuentro de trabajo de la Red EDIL Andaluc\u00eda, una iniciativa impulsada por la FAMP en el marco del Comit\u00e9 para el Desarrollo Urbano Sostenible e Integrado de Andaluc\u00eda, Comit\u00e9 DUSIA, con el objetivo de acompa\u00f1ar a las entidades locales andaluzas beneficiarias de la senda financiera FEDER 2021\u20132027 en la puesta en marcha y ejecuci\u00f3n de sus Planes de Actuaci\u00f3n Integrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada, celebrada en las oficinas centrales de EMASESA, ha reunido a responsables pol\u00edticos y t\u00e9cnicos municipales en un momento clave para la implementaci\u00f3n de los PAI, con una programaci\u00f3n orientada tanto a la gesti\u00f3n operativa de los fondos como a la capitalizaci\u00f3n estrat\u00e9gica de los proyectos urbanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, la secretaria general de la FAMP, Yolanda S\u00e1ez, ha puesto en valor el papel de la Red EDIL Andaluc\u00eda como \u201cinstrumento de acompa\u00f1amiento, formaci\u00f3n especializada y cooperaci\u00f3n entre entidades locales\u201d. Ha destacado que, tras seis meses de exitosa andadura, la Red \u201cha demostrado que era necesaria, que est\u00e1 siendo \u00fatil y que tiene recorrido para seguir creciendo y reforz\u00e1ndose en los pr\u00f3ximos meses\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria general de la FAMP ha subrayado que la convocatoria vinculada a los Planes de Actuaci\u00f3n Integrados representa \u201cuna oportunidad hist\u00f3rica\u201d para los municipios, diputaciones y mancomunidades andaluzas, tanto por el volumen de recursos movilizados como por su capacidad transformadora. En este sentido, ha recordado que \u201cAndaluc\u00eda afronta uno de los mayores retos de desarrollo y gesti\u00f3n urbana de las \u00faltimas d\u00e9cadas, con una inversi\u00f3n global superior a los 865 millones de euros, de los cuales m\u00e1s de 735 millones proceden de financiaci\u00f3n europea\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro ha incluido un di\u00e1logo inicial bajo el t\u00edtulo \u201cFondos europeos para hacer ciudad: el papel del liderazgo municipal en la ejecuci\u00f3n del PAI\u201d, en el que han participado el coordinador general de la FAMP, Manuel Garc\u00eda, y la tercera teniente de alcalde y concejala de Fondos Europeos, Agenda Urbana, Sostenibilidad, Planes Estrat\u00e9gicos y Proyecci\u00f3n del Ayuntamiento de Sevilla, Minerva Salas. La sesi\u00f3n ha sido conducida por Sergio Serna, Socio-Director de TECH friendly. Manuel Garc\u00eda ha incidido en la necesidad de ofrecer a las entidades locales \u201cun instrumento \u00fatil, pr\u00e1ctico y cercano\u201d que les permita afrontar con mayores garant\u00edas la ejecuci\u00f3n de los fondos europeos. \u201cNo se trata solo de acompa\u00f1ar la gesti\u00f3n de unos fondos, sino de ayudar a las entidades locales a convertir una gran oportunidad financiera en proyectos reales, en transformaciones urbanas bien ejecutadas y en mejoras tangibles para la ciudadan\u00eda andaluza\u201d. Por su parte, Minerva Salas, ha hecho hincapi\u00e9 en la capacidad transformadora de estos fondos a trav\u00e9s de proyectos que van a permitir dise\u00f1ar el futuro de ciudades sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada tambi\u00e9n ha abordado la capitalizaci\u00f3n de los PAI como una oportunidad para multiplicar el impacto de las actuaciones y posicionar a las ciudades andaluzas en el panorama espa\u00f1ol y europeo del desarrollo urbano integrado. Adem\u00e1s, se ha desarrollado un taller pr\u00e1ctico centrado en cuestiones clave para la ejecuci\u00f3n, como la selecci\u00f3n de operaciones, la solicitud de pago de reembolso, la gesti\u00f3n documental, el seguimiento de indicadores, los requisitos ambientales, la trazabilidad y la justificaci\u00f3n de gastos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria general de la FAMP ha querido subrayar la buena acogida de la Red EDIL Andaluc\u00eda desde su puesta en marcha. Las acciones formativas celebradas hasta la fecha han registrado una participaci\u00f3n media superior a las 110 o 120 personas, lo que evidencia, seg\u00fan la Federaci\u00f3n, \u201cla necesidad real de acompa\u00f1amiento t\u00e9cnico y la utilidad de los contenidos ofrecidos a responsables pol\u00edticos y equipos t\u00e9cnicos municipales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, desde la FAMP se ha avanzado en las principales l\u00edneas del nuevo Plan de Trabajo de la Red EDIL Andaluc\u00eda para el pr\u00f3ximo semestre. Entre ellas figuran un segundo ciclo de webinars formativos orientados a la ejecuci\u00f3n pr\u00e1ctica del PAI; un nuevo ciclo de buenas pr\u00e1cticas de entidades locales; la continuidad del buz\u00f3n t\u00e9cnico de consultas como herramienta de asesoramiento especializado; y la celebraci\u00f3n de un nuevo encuentro presencial en las primeras semanas de 2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este segundo encuentro, la FAMP da continuidad al trabajo iniciado en noviembre de 2025 en M\u00e1laga, donde se present\u00f3 y constituy\u00f3 la Red EDIL Andaluc\u00eda. La cita de Sevilla marca, adem\u00e1s, el cierre de una primera fase de impulso y apertura de la Red y el inicio de una nueva etapa de consolidaci\u00f3n, con una orientaci\u00f3n m\u00e1s pr\u00e1ctica, adaptada a las necesidades reales de ejecuci\u00f3n de los municipios andaluces. Se reafirma as\u00ed el compromiso con el desarrollo urbano sostenible, la innovaci\u00f3n, la cohesi\u00f3n territorial y el papel de las administraciones locales como motores del cambio. La Red EDIL Andaluc\u00eda continuar\u00e1 trabajando para que ninguna entidad local andaluza afronte sola el reto de ejecutar sus Planes de Actuaci\u00f3n Integrados y para que los fondos europeos se traduzcan en resultados reales para el conjunto de Andaluc\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 2\u00ba Encuentro de trabajo re\u00fane en Sevilla a entidades locales para avanzar en la gesti\u00f3n de los Planes de Actuaci\u00f3n Integrados y abrir una nueva etapa de consolidaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1082","inline_featured_image":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA\" \/>\n<meta property=\"og:description\" content=\"El 2\u00ba Encuentro de trabajo re\u00fane en Sevilla a entidades locales para avanzar en la gesti\u00f3n de los Planes de Actuaci\u00f3n Integrados y abrir una nueva etapa de consolidaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/\" \/>\n<meta property=\"og:site_name\" content=\"DUSIA\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-20T10:41:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T10:41:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DUSIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DUSIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/\",\"url\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/\",\"name\":\"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA\",\"isPartOf\":{\"@id\":\"https:\/\/dusia.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg\",\"datePublished\":\"2026-05-20T10:41:53+00:00\",\"dateModified\":\"2026-05-20T10:41:54+00:00\",\"author\":{\"@id\":\"https:\/\/dusia.es\/#\/schema\/person\/ff50c968cea187fac8a299b9da3bdbb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage\",\"url\":\"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg\",\"contentUrl\":\"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg\",\"width\":1600,\"height\":896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dusia.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dusia.es\/#website\",\"url\":\"https:\/\/dusia.es\/\",\"name\":\"DUSIA\",\"description\":\"Comit&eacute; para el Desarrollo Urbano, Sostenible e Integrado de Andaluc&iacute;a.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dusia.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dusia.es\/#\/schema\/person\/ff50c968cea187fac8a299b9da3bdbb1\",\"name\":\"DUSIA\",\"sameAs\":[\"http:\/\/dusia.es\"],\"url\":\"https:\/\/dusia.es\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/","og_locale":"es_ES","og_type":"article","og_title":"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA","og_description":"El 2\u00ba Encuentro de trabajo re\u00fane en Sevilla a entidades locales para avanzar en la gesti\u00f3n de los Planes de Actuaci\u00f3n Integrados y abrir una nueva etapa de consolidaci\u00f3n de [&hellip;]","og_url":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/","og_site_name":"DUSIA","article_published_time":"2026-05-20T10:41:53+00:00","article_modified_time":"2026-05-20T10:41:54+00:00","og_image":[{"width":1600,"height":896,"url":"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg","type":"image\/jpeg"}],"author":"DUSIA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"DUSIA","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/","url":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/","name":"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local - DUSIA","isPartOf":{"@id":"https:\/\/dusia.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage"},"image":{"@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage"},"thumbnailUrl":"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg","datePublished":"2026-05-20T10:41:53+00:00","dateModified":"2026-05-20T10:41:54+00:00","author":{"@id":"https:\/\/dusia.es\/#\/schema\/person\/ff50c968cea187fac8a299b9da3bdbb1"},"breadcrumb":{"@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#primaryimage","url":"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg","contentUrl":"https:\/\/dusia.es\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-20-at-12.12.26-2-e1779273703865.jpeg","width":1600,"height":896},{"@type":"BreadcrumbList","@id":"https:\/\/dusia.es\/index.php\/2026\/05\/20\/la-famp-refuerza-en-sevilla-la-red-edil-andalucia-como-espacio-de-apoyo-tecnico-para-la-ejecucion-de-los-fondos-europeos-en-el-ambito-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dusia.es\/"},{"@type":"ListItem","position":2,"name":"La FAMP refuerza en Sevilla la Red EDIL Andaluc\u00eda como espacio de apoyo t\u00e9cnico para la ejecuci\u00f3n de los fondos europeos en el \u00e1mbito local"}]},{"@type":"WebSite","@id":"https:\/\/dusia.es\/#website","url":"https:\/\/dusia.es\/","name":"DUSIA","description":"Comit&eacute; para el Desarrollo Urbano, Sostenible e Integrado de Andaluc&iacute;a.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dusia.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dusia.es\/#\/schema\/person\/ff50c968cea187fac8a299b9da3bdbb1","name":"DUSIA","sameAs":["http:\/\/dusia.es"],"url":"https:\/\/dusia.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":1,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"predecessor-version":[{"id":613,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/posts\/611\/revisions\/613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/media\/612"}],"wp:attachment":[{"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dusia.es\/index.php\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}